{"id":28127,"date":"2026-05-22T00:00:00","date_gmt":"2026-05-21T22:00:00","guid":{"rendered":"https:\/\/foerdecard.com\/veranstaltungen\/magic-moments-18\/"},"modified":"2026-04-26T06:00:23","modified_gmt":"2026-04-26T04:00:23","slug":"magic-moments-18","status":"publish","type":"veranstaltungen","link":"https:\/\/foerdecard.com\/da\/veranstaltungen\/magic-moments-18\/","title":{"rendered":"Magic Moments"},"content":{"rendered":"<div id=\"modal-ready\"><p>Kostbare Momente genie\u00dfen, abschalten und neue Energie tanken \u2013 f\u00fcr mich ganz alleine, zu zweit oder mit Freunden.\u00a0<\/p>\n<p>Ein Zufluchtsort zum Aufzutanken f\u00fcr neue Inspirationen ist Das James mit seinen unendlich vielen M\u00f6glichkeiten: Unser 2000 m\u00b2 umfassendes Spa &#8220;Five Senses&#8221; l\u00e4dt ein zu Entspannung pur; der Rooftop-Pool mit Panoramablick \u00fcber die F\u00f6rde ist ein wunderbares Erlebnis.\u00a0<\/p>\n<p>Starten Sie mit einem k\u00f6stlichen Fr\u00fchst\u00fcck im Restaurant James Farmhouse in den Tag, bevor Sie im SPA abtauchen.\u00a0<\/p>\n<p>MAGIC MOMENTS<br \/>\n(von Montag bis Freitag auf Anfrage nach Verf\u00fcgbarkeit. )\u00a0<\/p>\n<p>James Farmhouse Fr\u00fchst\u00fccksbuffet von 8:00 \u2013 10:00 Uhr\u00a0<br \/>\nSPA-Zutritt von 10:00 \u2013 15:00 Uhr<br \/>\nKuscheliger Bademantel &#038; Handt\u00fccher zum Verweilen<br \/>\nEntspannen in der Saunawelt sowie in unseren Ruhezonen<br \/>\nRooftop-Pool zum Baden und Relaxen am Kamin\u00a0<\/p>\n<p>Preis: 95 EUR pro Gast<\/p>\n<p>Reservierung: https:\/\/www.dasjames.com\/spa\/day-spa\/magic-moments<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Kostbare Momente genie\u00dfen, abschalten und neue Energie tanken \u2013 f\u00fcr mich ganz alleine, zu zweit oder mit Freunden.\u00a0 Ein Zufluchtsort zum Aufzutanken f\u00fcr neue Inspirationen ist Das James mit seinen unendlich vielen M\u00f6glichkeiten: Unser 2000 m\u00b2 umfassendes Spa &#8220;Five Senses&#8221; l\u00e4dt ein zu Entspannung pur; der Rooftop-Pool mit Panoramablick \u00fcber die F\u00f6rde ist ein wunderbares [&hellip;]<\/p>\n","protected":false},"featured_media":28117,"parent":0,"template":"","steuerung":[],"class_list":["post-28127","veranstaltungen","type-veranstaltungen","status-publish","has-post-thumbnail","hentry"],"acf":{"veranstaltungsort_name":"Das James, F\u00f6rdepromenade 30, Flensburg","veranstaltungsort_strasse":"","veranstaltungsort_plz":"","veranstaltungsort_stadt":"","startzeitpunkt":"2026-05-22 00:00","endzeitpunkt":null},"featured_image_url":"https:\/\/foerdecard.com\/wp-content\/uploads\/E1313953680069684796_FN-FeratelFlensburg_1777008354.jpg","categories":null,"_links":{"self":[{"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/veranstaltungen\/28127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/media\/28117"}],"wp:attachment":[{"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/media?parent=28127"}],"wp:term":[{"taxonomy":"steuerung","embeddable":true,"href":"https:\/\/foerdecard.com\/da\/wp-json\/wp\/v2\/steuerung?post=28127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}