{"id":29180,"date":"2026-06-09T11:00:00","date_gmt":"2026-06-09T09:00:00","guid":{"rendered":"https:\/\/foerdecard.com\/veranstaltungen\/running-city-tours-joggen-sightseeing-verbinden-7\/"},"modified":"2026-05-13T12:17:00","modified_gmt":"2026-05-13T10:17:00","slug":"running-city-tours-joggen-sightseeing-verbinden-7","status":"publish","type":"veranstaltungen","link":"https:\/\/foerdecard.com\/en\/veranstaltungen\/running-city-tours-joggen-sightseeing-verbinden-7\/","title":{"rendered":"Running City Tours &#8211; Joggen &#038; Sightseeing verbinden"},"content":{"rendered":"<div id=\"modal-ready\"><p>Die sportliche Stadtf\u00fchrung: Lauftouren mit lokalem Guide<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Die sportliche Stadtf\u00fchrung: Lauftouren mit lokalem Guide<\/p>\n","protected":false},"featured_media":29172,"parent":0,"template":"","steuerung":[],"class_list":["post-29180","veranstaltungen","type-veranstaltungen","status-publish","has-post-thumbnail","hentry"],"acf":{"veranstaltungsort_name":"Treffpunkt: Deutsches Haus (Berliner Platz 1)","veranstaltungsort_strasse":"","veranstaltungsort_plz":"","veranstaltungsort_stadt":"","startzeitpunkt":"2026-06-09 11:00","endzeitpunkt":null},"featured_image_url":"https:\/\/foerdecard.com\/wp-content\/uploads\/E4869311252890221035_FN-FeratelFlensburg_1778494138.jpg","categories":null,"_links":{"self":[{"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/veranstaltungen\/29180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/media\/29172"}],"wp:attachment":[{"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/media?parent=29180"}],"wp:term":[{"taxonomy":"steuerung","embeddable":true,"href":"https:\/\/foerdecard.com\/en\/wp-json\/wp\/v2\/steuerung?post=29180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}